{"id":650,"count":2,"description":"","link":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/","name":"Plattform und Community","slug":"plattform-und-community","taxonomy":"category","parent":581,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plattform und Community Archives - It&#039;s Complicated<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plattform und Community Archives - It&#039;s Complicated\" \/>\n<meta property=\"og:url\" content=\"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/\" \/>\n<meta property=\"og:site_name\" content=\"It&#039;s Complicated\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/category\\\/fur-therapeuten\\\/plattform-und-community\\\/\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/category\\\/fur-therapeuten\\\/plattform-und-community\\\/\",\"name\":\"Plattform und Community Archives - It&#039;s Complicated\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/category\\\/fur-therapeuten\\\/plattform-und-community\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/category\\\/fur-therapeuten\\\/plattform-und-community\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plattform und Community\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/\",\"name\":\"It's Complicated\",\"description\":\"Life is complicated. Finding a therapist shouldn&#039;t be.\",\"publisher\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#organization\",\"name\":\"It's Complicated\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/tilted_d_square_green.png\",\"contentUrl\":\"https:\\\/\\\/complicated.life\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/tilted_d_square_green.png\",\"width\":500,\"height\":500,\"caption\":\"It's Complicated\"},\"image\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/complicated___life\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/its-complicated\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plattform und Community Archives - It&#039;s Complicated","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/","og_locale":"de_DE","og_type":"article","og_title":"Plattform und Community Archives - It&#039;s Complicated","og_url":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/","og_site_name":"It&#039;s Complicated","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/","url":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/","name":"Plattform und Community Archives - It&#039;s Complicated","isPartOf":{"@id":"https:\/\/complicated.life\/blog\/de\/#website"},"breadcrumb":{"@id":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/complicated.life\/blog\/de\/category\/fur-therapeuten\/plattform-und-community\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/complicated.life\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Plattform und Community"}]},{"@type":"WebSite","@id":"https:\/\/complicated.life\/blog\/de\/#website","url":"https:\/\/complicated.life\/blog\/de\/","name":"It's Complicated","description":"Life is complicated. Finding a therapist shouldn&#039;t be.","publisher":{"@id":"https:\/\/complicated.life\/blog\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/complicated.life\/blog\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/complicated.life\/blog\/de\/#organization","name":"It's Complicated","url":"https:\/\/complicated.life\/blog\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/complicated.life\/blog\/de\/#\/schema\/logo\/image\/","url":"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2023\/09\/tilted_d_square_green.png","contentUrl":"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2023\/09\/tilted_d_square_green.png","width":500,"height":500,"caption":"It's Complicated"},"image":{"@id":"https:\/\/complicated.life\/blog\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/complicated___life\/","https:\/\/www.linkedin.com\/company\/its-complicated"]}]}},"_links":{"self":[{"href":"https:\/\/complicated.life\/blog\/de\/wp-json\/wp\/v2\/categories\/650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/complicated.life\/blog\/de\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/complicated.life\/blog\/de\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/complicated.life\/blog\/de\/wp-json\/wp\/v2\/categories\/581"}],"wp:post_type":[{"href":"https:\/\/complicated.life\/blog\/de\/wp-json\/wp\/v2\/posts?categories=650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}