{"id":6,"name":"Philip Sheldon","url":"https:\/\/www.complicated.life\/find-a-therapist\/berlin\/philip-sheldon","description":"therapy, for me, is a space to explore what's happened in the past, what's going on now, and what might happen next, and to navigate these sometimes difficult roads we have experienced in order to get back to ourselves","link":"https:\/\/complicated.life\/blog\/author\/phil\/","slug":"phil","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Philip Sheldon, Author at It&#039;s Complicated<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/complicated.life\/blog\/author\/phil\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Philip Sheldon, Author at It&#039;s Complicated\" \/>\n<meta property=\"og:url\" content=\"https:\/\/complicated.life\/blog\/author\/phil\/\" \/>\n<meta property=\"og:site_name\" content=\"It&#039;s Complicated\" \/>\n<meta property=\"og:image\" content=\"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2019\/07\/Screen-Shot-2019-07-25-at-13.12.53.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/\",\"name\":\"Philip Sheldon, Author at It&#039;s Complicated\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/complicated.life\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Archives for Philip Sheldon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/\",\"name\":\"It's Complicated\",\"description\":\"Life is complicated. Finding a therapist shouldn&#039;t be.\",\"publisher\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/complicated.life\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#organization\",\"name\":\"It's Complicated\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/complicated.life\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/tilted_d_square_green.png\",\"contentUrl\":\"https:\\\/\\\/complicated.life\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/tilted_d_square_green.png\",\"width\":500,\"height\":500,\"caption\":\"It's Complicated\"},\"image\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/complicated___life\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/its-complicated\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/#\\\/schema\\\/person\\\/e4970b48679ac984a20f8adcbf9aa112\",\"name\":\"Philip Sheldon\",\"description\":\"therapy, for me, is a space to explore what's happened in the past, what's going on now, and what might happen next, and to navigate these sometimes difficult roads we have experienced in order to get back to ourselves\",\"sameAs\":[\"https:\\\/\\\/www.complicated.life\\\/find-a-therapist\\\/berlin\\\/philip-sheldon\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/complicated.life\\\/blog\\\/author\\\/phil\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Philip Sheldon, Author at It&#039;s Complicated","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/complicated.life\/blog\/author\/phil\/","og_locale":"en_US","og_type":"profile","og_title":"Philip Sheldon, Author at It&#039;s Complicated","og_url":"https:\/\/complicated.life\/blog\/author\/phil\/","og_site_name":"It&#039;s Complicated","og_image":[{"url":"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2019\/07\/Screen-Shot-2019-07-25-at-13.12.53.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/complicated.life\/blog\/author\/phil\/","url":"https:\/\/complicated.life\/blog\/author\/phil\/","name":"Philip Sheldon, Author at It&#039;s Complicated","isPartOf":{"@id":"https:\/\/complicated.life\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/complicated.life\/blog\/author\/phil\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/complicated.life\/blog\/author\/phil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/complicated.life\/blog\/author\/phil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/complicated.life\/blog\/"},{"@type":"ListItem","position":2,"name":"Archives for Philip Sheldon"}]},{"@type":"WebSite","@id":"https:\/\/complicated.life\/blog\/#website","url":"https:\/\/complicated.life\/blog\/","name":"It's Complicated","description":"Life is complicated. Finding a therapist shouldn&#039;t be.","publisher":{"@id":"https:\/\/complicated.life\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/complicated.life\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/complicated.life\/blog\/#organization","name":"It's Complicated","url":"https:\/\/complicated.life\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/complicated.life\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2023\/09\/tilted_d_square_green.png","contentUrl":"https:\/\/complicated.life\/blog\/wp-content\/uploads\/2023\/09\/tilted_d_square_green.png","width":500,"height":500,"caption":"It's Complicated"},"image":{"@id":"https:\/\/complicated.life\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/complicated___life\/","https:\/\/www.linkedin.com\/company\/its-complicated"]},{"@type":"Person","@id":"https:\/\/complicated.life\/blog\/#\/schema\/person\/e4970b48679ac984a20f8adcbf9aa112","name":"Philip Sheldon","description":"therapy, for me, is a space to explore what's happened in the past, what's going on now, and what might happen next, and to navigate these sometimes difficult roads we have experienced in order to get back to ourselves","sameAs":["https:\/\/www.complicated.life\/find-a-therapist\/berlin\/philip-sheldon"],"mainEntityOfPage":{"@id":"https:\/\/complicated.life\/blog\/author\/phil\/"}}]}},"_links":{"self":[{"href":"https:\/\/complicated.life\/blog\/wp-json\/wp\/v2\/users\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/complicated.life\/blog\/wp-json\/wp\/v2\/users"}]}}